{"id":238354,"date":"2025-10-31T10:11:41","date_gmt":"2025-10-31T09:11:41","guid":{"rendered":"https:\/\/moto-screenies.de\/produkt\/steinschlag-lackschutz-tankschutzfolie-ppf-schutzfolie-fuer-kawasaki-z1000sx-2014-2016\/"},"modified":"2026-01-26T16:08:07","modified_gmt":"2026-01-26T15:08:07","slug":"steinschlag-lackschutz-tankschutzfolie-ppf-schutzfolie-fuer-kawasaki-z1000sx-2014-2016","status":"publish","type":"product","link":"https:\/\/moto-screenies.de\/en\/produkt\/steinschlag-lackschutz-tankschutzfolie-ppf-schutzfolie-fuer-kawasaki-z1000sx-2014-2016\/","title":{"rendered":"Steinschlag Lackschutz &#8211; Tankschutzfolie PPF Schutzfolie f\u00fcr Kawasaki Z1000SX 2014-2016"},"content":{"rendered":"<p>Erlebe den optimalen Lackschutz f\u00fcr dein Motorrad mit unserer hochwertigen Schutzfolie \u2013 entwickelt f\u00fcr h\u00f6chste Anspr\u00fcche und eine perfekte Passform.<\/p>\n<p>Unsere ma\u00dfgeschneiderte Lackschutzfolie f\u00fcr Kawasaki Z1000SX 2014-2016 vereint modernste Materialien mit pr\u00e4ziser Fertigung, um dein Bike zuverl\u00e4ssig vor Steinschl\u00e4gen, Kratzern und Witterungseinfl\u00fcssen zu sch\u00fctzen \u2013 ohne die Optik zu ver\u00e4ndern.<br \/>\nDie Folie besteht aus hochwertigem Oraguard-TPU-Material, das Aufprallenergie effektiv absorbiert und selbst unter extremen Bedingungen formstabil bleibt.<br \/>\nDie glatte, schmutzabweisende Oberfl\u00e4che erm\u00f6glicht eine einfache Reinigung \u2013 ein feuchtes Tuch gen\u00fcgt.<br \/>\nDank der Technologie aus der Automobil- und Luftfahrtindustrie profitierst du von einer au\u00dfergew\u00f6hnlich langen Lebensdauer und dauerhafter Transparenz.<br \/>\nIm kompletten Montagekit ist alles enthalten: passgenaue Schutzfolien, Montageanleitung, Videoguide und Reinigungstuch.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Passgenaue Lackschutzfolie f\u00fcr Kawasaki Z1000SX 2014-2016 \u2013 sch\u00fctzt zuverl\u00e4ssig vor Steinschl\u00e4gen und Kratzern. Hochwertiges TPU-Material mit einfacher Reinigung und langer Lebensdauer.<\/p>\n","protected":false},"featured_media":243264,"comment_status":"open","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_uf_show_specific_survey":0,"_uf_disable_surveys":false},"product_brand":[],"product_cat":[424],"product_tag":[189],"class_list":{"0":"post-238354","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-kawasaki-schutzfolie-fuer-dein-motorrad","7":"product_tag-lackschutzfolie","8":"product_shipping_class-standard","10":"first","11":"instock","12":"taxable","13":"shipping-taxable","14":"purchasable","15":"product-type-variable"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Steinschlag Lackschutz - Tankschutzfolie PPF Schutzfolie f\u00fcr Kawasaki Z1000SX 2014-2016<\/title>\n<meta name=\"description\" content=\"Ma\u00dfgeschneiderte Lackschutzfolie f\u00fcr Kawasaki Z1000SX 2014-2016. Hochwertiger TPU-Schutz gegen Kratzer, Steinschl\u00e4ge und Witterungseinfl\u00fcsse.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/moto-screenies.de\/en\/produkt\/steinschlag-lackschutz-tankschutzfolie-ppf-schutzfolie-fuer-kawasaki-z1000sx-2014-2016\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Steinschlag Lackschutz - Tankschutzfolie PPF Schutzfolie f\u00fcr Kawasaki Z1000SX 2014-2016\" \/>\n<meta property=\"og:description\" content=\"Ma\u00dfgeschneiderte Lackschutzfolie f\u00fcr Kawasaki Z1000SX 2014-2016. Hochwertiger TPU-Schutz gegen Kratzer, Steinschl\u00e4ge und Witterungseinfl\u00fcsse.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/moto-screenies.de\/en\/produkt\/steinschlag-lackschutz-tankschutzfolie-ppf-schutzfolie-fuer-kawasaki-z1000sx-2014-2016\/\" \/>\n<meta property=\"og:site_name\" content=\"Moto Screenies\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-26T15:08:07+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/moto-screenies.de\\\/en\\\/produkt\\\/steinschlag-lackschutz-tankschutzfolie-ppf-schutzfolie-fuer-kawasaki-z1000sx-2014-2016\\\/\",\"url\":\"https:\\\/\\\/moto-screenies.de\\\/en\\\/produkt\\\/steinschlag-lackschutz-tankschutzfolie-ppf-schutzfolie-fuer-kawasaki-z1000sx-2014-2016\\\/\",\"name\":\"Steinschlag Lackschutz - Tankschutzfolie PPF Schutzfolie f\u00fcr Kawasaki Z1000SX 2014-2016\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/moto-screenies.de\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/moto-screenies.de\\\/en\\\/produkt\\\/steinschlag-lackschutz-tankschutzfolie-ppf-schutzfolie-fuer-kawasaki-z1000sx-2014-2016\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/moto-screenies.de\\\/en\\\/produkt\\\/steinschlag-lackschutz-tankschutzfolie-ppf-schutzfolie-fuer-kawasaki-z1000sx-2014-2016\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/moto-screenies.de\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/1154516_Product.jpg\",\"datePublished\":\"2025-10-31T09:11:41+00:00\",\"dateModified\":\"2026-01-26T15:08:07+00:00\",\"description\":\"Ma\u00dfgeschneiderte Lackschutzfolie f\u00fcr Kawasaki Z1000SX 2014-2016. Hochwertiger TPU-Schutz gegen Kratzer, Steinschl\u00e4ge und Witterungseinfl\u00fcsse.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/moto-screenies.de\\\/en\\\/produkt\\\/steinschlag-lackschutz-tankschutzfolie-ppf-schutzfolie-fuer-kawasaki-z1000sx-2014-2016\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/moto-screenies.de\\\/en\\\/produkt\\\/steinschlag-lackschutz-tankschutzfolie-ppf-schutzfolie-fuer-kawasaki-z1000sx-2014-2016\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/moto-screenies.de\\\/en\\\/produkt\\\/steinschlag-lackschutz-tankschutzfolie-ppf-schutzfolie-fuer-kawasaki-z1000sx-2014-2016\\\/#primaryimage\",\"url\":\"https:\\\/\\\/moto-screenies.de\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/1154516_Product.jpg\",\"contentUrl\":\"https:\\\/\\\/moto-screenies.de\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/1154516_Product.jpg\",\"width\":1600,\"height\":1600,\"caption\":\"PP58-1\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/moto-screenies.de\\\/en\\\/produkt\\\/steinschlag-lackschutz-tankschutzfolie-ppf-schutzfolie-fuer-kawasaki-z1000sx-2014-2016\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/moto-screenies.de\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Store\",\"item\":\"https:\\\/\\\/moto-screenies.com\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Steinschlag Lackschutz &#8211; Tankschutzfolie PPF Schutzfolie f\u00fcr Kawasaki Z1000SX 2014-2016\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/moto-screenies.de\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/moto-screenies.de\\\/en\\\/\",\"name\":\"Moto Screenies\",\"description\":\"Die Displayschutzfolie f\u00fcr dein Motorrad\",\"publisher\":{\"@id\":\"https:\\\/\\\/moto-screenies.de\\\/en\\\/#organization\"},\"alternateName\":\"MS\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/moto-screenies.de\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/moto-screenies.de\\\/en\\\/#organization\",\"name\":\"Moto Screenies\",\"url\":\"https:\\\/\\\/moto-screenies.de\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/moto-screenies.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Moto Screenies\"},\"image\":{\"@id\":\"https:\\\/\\\/moto-screenies.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Steinschlag Lackschutz - Tankschutzfolie PPF Schutzfolie f\u00fcr Kawasaki Z1000SX 2014-2016","description":"Ma\u00dfgeschneiderte Lackschutzfolie f\u00fcr Kawasaki Z1000SX 2014-2016. Hochwertiger TPU-Schutz gegen Kratzer, Steinschl\u00e4ge und Witterungseinfl\u00fcsse.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/moto-screenies.de\/en\/produkt\/steinschlag-lackschutz-tankschutzfolie-ppf-schutzfolie-fuer-kawasaki-z1000sx-2014-2016\/","og_locale":"en_US","og_type":"article","og_title":"Steinschlag Lackschutz - Tankschutzfolie PPF Schutzfolie f\u00fcr Kawasaki Z1000SX 2014-2016","og_description":"Ma\u00dfgeschneiderte Lackschutzfolie f\u00fcr Kawasaki Z1000SX 2014-2016. Hochwertiger TPU-Schutz gegen Kratzer, Steinschl\u00e4ge und Witterungseinfl\u00fcsse.","og_url":"https:\/\/moto-screenies.de\/en\/produkt\/steinschlag-lackschutz-tankschutzfolie-ppf-schutzfolie-fuer-kawasaki-z1000sx-2014-2016\/","og_site_name":"Moto Screenies","article_modified_time":"2026-01-26T15:08:07+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/moto-screenies.de\/en\/produkt\/steinschlag-lackschutz-tankschutzfolie-ppf-schutzfolie-fuer-kawasaki-z1000sx-2014-2016\/","url":"https:\/\/moto-screenies.de\/en\/produkt\/steinschlag-lackschutz-tankschutzfolie-ppf-schutzfolie-fuer-kawasaki-z1000sx-2014-2016\/","name":"Steinschlag Lackschutz - Tankschutzfolie PPF Schutzfolie f\u00fcr Kawasaki Z1000SX 2014-2016","isPartOf":{"@id":"https:\/\/moto-screenies.de\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/moto-screenies.de\/en\/produkt\/steinschlag-lackschutz-tankschutzfolie-ppf-schutzfolie-fuer-kawasaki-z1000sx-2014-2016\/#primaryimage"},"image":{"@id":"https:\/\/moto-screenies.de\/en\/produkt\/steinschlag-lackschutz-tankschutzfolie-ppf-schutzfolie-fuer-kawasaki-z1000sx-2014-2016\/#primaryimage"},"thumbnailUrl":"https:\/\/moto-screenies.de\/wp-content\/uploads\/2025\/11\/1154516_Product.jpg","datePublished":"2025-10-31T09:11:41+00:00","dateModified":"2026-01-26T15:08:07+00:00","description":"Ma\u00dfgeschneiderte Lackschutzfolie f\u00fcr Kawasaki Z1000SX 2014-2016. Hochwertiger TPU-Schutz gegen Kratzer, Steinschl\u00e4ge und Witterungseinfl\u00fcsse.","breadcrumb":{"@id":"https:\/\/moto-screenies.de\/en\/produkt\/steinschlag-lackschutz-tankschutzfolie-ppf-schutzfolie-fuer-kawasaki-z1000sx-2014-2016\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/moto-screenies.de\/en\/produkt\/steinschlag-lackschutz-tankschutzfolie-ppf-schutzfolie-fuer-kawasaki-z1000sx-2014-2016\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/moto-screenies.de\/en\/produkt\/steinschlag-lackschutz-tankschutzfolie-ppf-schutzfolie-fuer-kawasaki-z1000sx-2014-2016\/#primaryimage","url":"https:\/\/moto-screenies.de\/wp-content\/uploads\/2025\/11\/1154516_Product.jpg","contentUrl":"https:\/\/moto-screenies.de\/wp-content\/uploads\/2025\/11\/1154516_Product.jpg","width":1600,"height":1600,"caption":"PP58-1"},{"@type":"BreadcrumbList","@id":"https:\/\/moto-screenies.de\/en\/produkt\/steinschlag-lackschutz-tankschutzfolie-ppf-schutzfolie-fuer-kawasaki-z1000sx-2014-2016\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/moto-screenies.de\/en\/"},{"@type":"ListItem","position":2,"name":"Store","item":"https:\/\/moto-screenies.com\/shop\/"},{"@type":"ListItem","position":3,"name":"Steinschlag Lackschutz &#8211; Tankschutzfolie PPF Schutzfolie f\u00fcr Kawasaki Z1000SX 2014-2016"}]},{"@type":"WebSite","@id":"https:\/\/moto-screenies.de\/en\/#website","url":"https:\/\/moto-screenies.de\/en\/","name":"Moto Screenies","description":"Die Displayschutzfolie f\u00fcr dein Motorrad","publisher":{"@id":"https:\/\/moto-screenies.de\/en\/#organization"},"alternateName":"MS","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/moto-screenies.de\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/moto-screenies.de\/en\/#organization","name":"Moto Screenies","url":"https:\/\/moto-screenies.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/moto-screenies.de\/en\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Moto Screenies"},"image":{"@id":"https:\/\/moto-screenies.de\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/moto-screenies.de\/en\/wp-json\/wp\/v2\/product\/238354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/moto-screenies.de\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/moto-screenies.de\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/moto-screenies.de\/en\/wp-json\/wp\/v2\/comments?post=238354"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/moto-screenies.de\/en\/wp-json\/wp\/v2\/media\/243264"}],"wp:attachment":[{"href":"https:\/\/moto-screenies.de\/en\/wp-json\/wp\/v2\/media?parent=238354"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/moto-screenies.de\/en\/wp-json\/wp\/v2\/product_brand?post=238354"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/moto-screenies.de\/en\/wp-json\/wp\/v2\/product_cat?post=238354"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/moto-screenies.de\/en\/wp-json\/wp\/v2\/product_tag?post=238354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}